{"id":1644,"date":"2022-12-01T14:57:08","date_gmt":"2022-12-01T17:57:08","guid":{"rendered":"https:\/\/vitrinedafama.com.br\/?p=1644"},"modified":"2022-12-01T14:57:10","modified_gmt":"2022-12-01T17:57:10","slug":"quintal-do-espeto-reune-torcedores-nos-jogos-do-brasil","status":"publish","type":"post","link":"https:\/\/vitrinedafama.com.br\/index.php\/2022\/12\/01\/quintal-do-espeto-reune-torcedores-nos-jogos-do-brasil\/","title":{"rendered":"Quintal do Espeto re\u00fane torcedores nos jogos do Brasil"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em>Ingressos para assistir aos jogos est\u00e3o a partir de R$ 40 reais<\/em><br>O Brasil venceu os dois primeiros jogos e se prepara para as oitavas de final rumo a final e a rede Quintal do Espeto abre suas portas para receber a torcida animada da sele\u00e7\u00e3o brasileira em suas unidades e para o jogo contra os Camar\u00f5es que acontecer\u00e1 na pr\u00f3xima segunda-feira. Com variedade enorme de espetinhos, cerveja gelada e drinks especiais no sistema de comandas individuais.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A entrada est\u00e1 a partir de R$40 mas os clientes podemos optar pelo &#8220;Pacote Brasil&#8221; que custa R$160 (mulheres) e R$ 180 (homens) que inclui espetinhos b\u00e1sicos a vontade, op\u00e7\u00f5es veganas, por\u00e7\u00f5es de quibes e past\u00e9is, grande variedade de cervejas de marcas consagradas como Budweiser, Spaten, Original, Stella e Becks, refrigerante, \u00e1gua e \u00e1gua t\u00f4nica, al\u00e9m daquele atendimento de qualidade em ambiente familiar.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As reservas podem ser realizadas pelo telefone (11) 5095-6565 ou whatsapp 98314-0100. Disponibilidade de mesas e bistr\u00f4s, por ordem de chegada.&nbsp;<br>Os ingressos est\u00e3o dispon\u00edveis no site da Ticket 360. Veja qual a unidade mais pr\u00f3xima e vamos torcer pelo Brasil. Acesse&nbsp;<a href=\"https:\/\/bit.ly\/3MGyVyV\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/bit.ly\/3MGyVyV<\/a><br>Servi\u00e7o &#8211;&nbsp;Jogos do Brasil no Quintal do Espeto&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2 de dezembro: Brasil x Camar\u00f5es: <a href=\"https:\/\/bit.ly\/3MGyVyV\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/bit.ly\/3MGyVyV<\/a><br>Reservas: (11) 5095-6565\/ 98314-0100 ou pelo site\u00a0<a href=\"http:\/\/quintaldoespeto.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">quintaldoespeto.com.br<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/vitrinedafama.com.br\/wp-content\/uploads\/2022\/12\/quintal_abril-19-1024x684.jpg\" alt=\"\" class=\"wp-image-1646\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Fotos: Divulga\u00e7\u00e3o<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ingressos para assistir aos jogos est\u00e3o a partir de R$ 40 reaisO Brasil venceu os dois primeiros jogos e se prepara para as oitavas de final rumo a final e a rede Quintal do Espeto abre suas portas para receber a torcida animada da sele\u00e7\u00e3o brasileira em suas unidades e para o jogo contra os [&hellip;]<\/p>\n","protected":false},"author":3003182825,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[301,300],"class_list":["post-1644","post","type-post","status-publish","format-standard","hentry","category-sem-categoria","tag-copa","tag-quintal-do-espeto"],"_links":{"self":[{"href":"https:\/\/vitrinedafama.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vitrinedafama.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vitrinedafama.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vitrinedafama.com.br\/index.php\/wp-json\/wp\/v2\/users\/3003182825"}],"replies":[{"embeddable":true,"href":"https:\/\/vitrinedafama.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1644"}],"version-history":[{"count":1,"href":"https:\/\/vitrinedafama.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1644\/revisions"}],"predecessor-version":[{"id":1647,"href":"https:\/\/vitrinedafama.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1644\/revisions\/1647"}],"wp:attachment":[{"href":"https:\/\/vitrinedafama.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vitrinedafama.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vitrinedafama.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}