{"id":1041,"date":"2022-04-06T04:43:28","date_gmt":"2022-04-06T07:43:28","guid":{"rendered":"https:\/\/vitrinedafama.com.br\/?p=1041"},"modified":"2022-04-06T04:43:30","modified_gmt":"2022-04-06T07:43:30","slug":"olivia-nobre-estreia-como-musa-do-camarote-lapa-na-sapucai","status":"publish","type":"post","link":"https:\/\/vitrinedafama.com.br\/index.php\/2022\/04\/06\/olivia-nobre-estreia-como-musa-do-camarote-lapa-na-sapucai\/","title":{"rendered":"Ol\u00edvia Nobre estreia como musa do Camarote Lapa na Sapuca\u00ed"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A cantora Ol\u00edvia Nobre, mais conhecida como Lily Nobre, fez sua estreia no carnaval carioca como musa do nov\u00edssimo camarote Lapa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A beldade, que completou recentemente 20 anos, no dia 12 de fevereiro, ser\u00e1 a musa do Camarote Lapa durante os desfiles das escolas de samba na Marqu\u00eas de Sapuca\u00ed. Filha mais velha do cantor e compositor Dudu Nobre e da dan\u00e7arina Adriana Bombom, Lily se lan\u00e7ou como cantora pop e aguarda para este ano, com ansiedade, o in\u00edcio da sua maratona de shows.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No \u00faltimo domingo, dia 03\/04, Lily Nobre esteve pela primeira vez na sapuca\u00ed para conhecer o camarote que vai representar, onde foi recebida com todas as honras pelos donos do Camarote Lapa, e tamb\u00e9m teve a ben\u00e7\u00e3o de um \u00edcone da avenida e do carnaval carioca, &nbsp;Selminha Sorriso, que \u00e9 Porta-bandeira da escola Beija-Flor de Nil\u00f3polis, e Embaixadora do Camarote Lapa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde pequena, a cantora se depara com o universo do samba atrav\u00e9s dos pais. Adriana Bombom possui hist\u00f3ria como rainha de bateria e Dudu Nobre \u00e9 um dos compositores do samba campe\u00e3o da Vila Isabel para 2022. \u201cEu tenho um la\u00e7o muito forte com o carnaval. Eu comecei a curtir a festa desde novinha por conta dos meus pais. Eu via a minha m\u00e3e se arrumando, meu pai saindo para cantar e sempre achei isso fascinante, ficava encantada. Por isso, sempre tive o carnaval muito aflorado em mim; de todas as festas que acontecem durante o ano, o carnaval \u00e9 a que eu mais amo\u201d, comentou a artista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Musa do estreante Camarote Lapa, que levar\u00e1 \u00e0 Sapuca\u00ed uma proposta diferente, como a bo\u00eamia, a diversidade do p\u00fablico e as tribos do bairro, situado na regi\u00e3o central da cidade, para Lily, a originalidade da Lapa ser\u00e1 o ponto forte do camarote. \u201cEu achei a proposta incr\u00edvel. A Lapa \u00e9 um dos locais mais diversos e queridinhos do Rio. \u00c9 muito inovador levar toda originalidade da Lapa para a dentro da Sapuca\u00ed.\u201d<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"1047\" src=\"https:\/\/vitrinedafama.com.br\/wp-content\/uploads\/2022\/04\/8e768a92-37cd-4ce2-96ef-c5f1979de1a9-1024x461.jpg\" alt=\"\" class=\"wp-image-1047\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"1043\" src=\"https:\/\/vitrinedafama.com.br\/wp-content\/uploads\/2022\/04\/87c45616-2973-4ec3-90c6-ce26ebf79b6a-756x1024.jpg\" alt=\"\" class=\"wp-image-1043\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"1044\" src=\"https:\/\/vitrinedafama.com.br\/wp-content\/uploads\/2022\/04\/e18b7b4a-7826-4208-bdb2-891444794d72-1024x461.jpg\" alt=\"\" class=\"wp-image-1044\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"1045\" src=\"https:\/\/vitrinedafama.com.br\/wp-content\/uploads\/2022\/04\/19c66b1b-7919-49e6-960a-54bfffffaf68-602x1024.jpg\" alt=\"\" class=\"wp-image-1045\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"1046\" src=\"https:\/\/vitrinedafama.com.br\/wp-content\/uploads\/2022\/04\/885ce7fd-3b18-4079-be16-5cfb94e36578-1024x773.jpg\" alt=\"\" class=\"wp-image-1046\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"1042\" src=\"https:\/\/vitrinedafama.com.br\/wp-content\/uploads\/2022\/04\/c99eb1bc-1dbd-435d-b150-24a04123d5e5.jpg\" alt=\"\" class=\"wp-image-1042\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>A cantora Ol\u00edvia Nobre, mais conhecida como Lily Nobre, fez sua estreia no carnaval carioca como musa do nov\u00edssimo camarote Lapa. A beldade, que completou recentemente 20 anos, no dia 12 de fevereiro, ser\u00e1 a musa do Camarote Lapa durante os desfiles das escolas de samba na Marqu\u00eas de Sapuca\u00ed. Filha mais velha do cantor [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1041","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/vitrinedafama.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vitrinedafama.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vitrinedafama.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vitrinedafama.com.br\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/vitrinedafama.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1041"}],"version-history":[{"count":1,"href":"https:\/\/vitrinedafama.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1041\/revisions"}],"predecessor-version":[{"id":1048,"href":"https:\/\/vitrinedafama.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1041\/revisions\/1048"}],"wp:attachment":[{"href":"https:\/\/vitrinedafama.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vitrinedafama.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vitrinedafama.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}